{"id":1638,"date":"2024-03-05T13:53:56","date_gmt":"2024-03-05T13:53:56","guid":{"rendered":"https:\/\/luckybastards.co\/\/?post_type=story&#038;p=1638"},"modified":"2025-09-13T17:43:59","modified_gmt":"2025-09-13T17:43:59","slug":"shades-of-fluorescent-playing-with-mexican-police","status":"publish","type":"story","link":"https:\/\/luckybastards.co\/fr\/story\/shades-of-fluorescent-playing-with-mexican-police\/","title":{"rendered":"Nuances de fluorescent : Jouer avec la police mexicaine"},"content":{"rendered":"<p id=\"e5d9\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Ce dimanche de novembre, je quitte Cancun (Mexique) pour San Jos\u00e9 (Costa Rica), o\u00f9 je dois retrouver ma m\u00e8re que j'ai invit\u00e9e de Paris pour que nous puissions voyager ensemble pendant 3 semaines au Costa Rica et \u00e0 Cuba.<\/p>\n<p id=\"0aca\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Juste avant l'embarquement, un membre du personnel de la compagnie a\u00e9rienne me demande de me soumettre \u00e0 des contr\u00f4les de s\u00e9curit\u00e9 suppl\u00e9mentaires aupr\u00e8s de la police douani\u00e8re mexicaine. N'ayant rien \u00e0 me reprocher, j'accepte sans sourciller.<\/p>\n<p id=\"54ad\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Je suis interrog\u00e9 par une polici\u00e8re qui veut en savoir plus sur mon voyage, mon s\u00e9jour au Mexique, mon projet pour le Costa Rica etc... les conneries habituelles. Ce n'est que lorsqu'elle me demande de poser mon sac sur la table pour proc\u00e9der \u00e0 une fouille que je commence \u00e0 changer de couleur. Une pens\u00e9e me traverse l'esprit. Pas une bonne. Je me souviens que j'ai encore des pilules d'ecstasy dans mon sac. Pas beaucoup, 7 ou 8. Mais certainement assez pour que le cher policier en face de moi me fasse rater mon vol. Ce qui est tout simplement impossible ! Il est hors de question que ma m\u00e8re reste seule \u00e0 l'a\u00e9roport de San Jos\u00e9, sans nouvelles de moi, sans savoir o\u00f9 aller, sans argent et sans connaissance de la langue. Ce n'est tout simplement pas possible et cela n'arrivera pas !<\/p>\n<p id=\"72c3\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Putain de Shane ! Un mec super sympa rencontr\u00e9 \u00e0 Austin (Texas) quelques semaines plus t\u00f4t. Il m'a h\u00e9berg\u00e9 quelques jours, on a fait des trucs tr\u00e8s cool ensemble, il m'a fait visiter la ville, m'a pr\u00e9sent\u00e9 \u00e0 ses amis, \u00e0 des filles, etc. Un gars super accueillant que je n'oublierai pas ! Quand je suis parti, Shane a insist\u00e9 pour m'offrir quelques pilules comme cadeau souvenir de sa part, et il ne tarissait pas d'\u00e9loges sur leur qualit\u00e9. Le fait est que je ne me drogue pas. Je veux dire que j'en ai essay\u00e9 plusieurs et que je plane de temps en temps, mais je suis loin d'\u00eatre une junkie. Je n'en ai donc pas mang\u00e9 une seule pendant le reste de mon s\u00e9jour aux \u00c9tats-Unis. En fait, ces pilules ont d\u00e9j\u00e0 voyag\u00e9 des \u00c9tats-Unis au Mexique, sans \u00eatre d\u00e9couvertes. En effet, \u00e0 mon arriv\u00e9e au Mexique, j'ai trouv\u00e9 dans ma valise la fameuse note laiss\u00e9e par les autorit\u00e9s am\u00e9ricaines lorsqu'elles ouvrent vos bagages et vous avertissent qu'elles ne sont pas responsables en cas de dommage ou de perte. Cette note avait \u00e9t\u00e9 laiss\u00e9e tout pr\u00e8s des pilules. Les idiots.<\/p>\n<p id=\"f899\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Quoi qu'il en soit, les circonstances semblent un peu plus compliqu\u00e9es aujourd'hui.<br \/>Pour \u00eatre honn\u00eate, je ne m'inqui\u00e8te pas particuli\u00e8rement de ma propre situation. Je ne pense pas que quelques pilules d'ecstasy puissent me causer trop d'ennuis dans un pays comme le Mexique, o\u00f9 ils ont des poissons bien plus gros \u00e0 attraper. Dans le pire des cas, quelques nuits dans une prison mexicaine ne me font pas sp\u00e9cialement peur.<\/p>\n<p id=\"ada2\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Ce qui m'effraie le plus, c'est la photo de ma m\u00e8re laiss\u00e9e seule \u00e0 l'a\u00e9roport de San Jos\u00e9. Cette vision de ma m\u00e8re vieillissante attendant des heures \u00e0 l'ext\u00e9rieur d'un a\u00e9roport \u00e0 l'autre bout du monde, ne sachant que faire ni o\u00f9 aller, abandonn\u00e9e par son propre fils, me remplit de honte et de chagrin. Je ne peux pas laisser ce cauchemar se r\u00e9aliser.<\/p>\n<p id=\"6b46\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Il est donc temps pour moi d'utiliser mes capacit\u00e9s intellectuelles et mon sens de la manipulation. Je commence \u00e0 r\u00e9fl\u00e9chir \u00e0 l'histoire que je vais raconter \u00e0 la polici\u00e8re, au ton que je vais employer, aux blagues que je vais faire... Tout ce que je peux faire pour qu'elle arr\u00eate sa putain de fouille !<\/p>\n<p id=\"9184\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Les pilules roses sont plac\u00e9es dans un sachet en plastique transparent contenant des bouchons d'oreille vert fluo, ce sachet se trouvant lui-m\u00eame dans ma trousse de voyage Air France avec une brosse \u00e0 dents, une cr\u00e8me hydratante et un masque de sommeil.\u00a0<strong class=\"kp jo\">Mon objectif est qu'elle n'atteigne pas ce sac en plastique transparent.<\/strong><\/p>\n<p id=\"4de3\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">La polici\u00e8re semble avoir une quarantaine d'ann\u00e9es. Originaire du Mexique, elle a probablement au moins 4 ou 5 enfants. En tant qu'officier de police, elle ne gagne probablement pas grand-chose. Avoir un de ses fils qui l'invite \u00e0 voyager \u00e0 travers le monde est probablement un r\u00eave pour elle. Des id\u00e9es pr\u00e9con\u00e7ues et racistes ? Je sais. Et je suis d'accord. Mais tant pis, j'y vais \u00e0 fond !<\/p>\n<p id=\"b461\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Pendant qu'elle fouille mon sac, je lui dis combien je suis heureux de rencontrer ma m\u00e8re, j'exprime toute la joie et le bonheur que je ressens \u00e0 l'id\u00e9e de la revoir, de la serrer dans mes bras, de partager des moments avec elle, apr\u00e8s tant de mois pass\u00e9s loin l'un de l'autre. Je lui parle de notre relation m\u00e8re-fils et je parle comme si j'\u00e9tais le meilleur et le plus aimant des fils au monde. Mais surtout, je ne la quitte pas des yeux. Je la regarde droit dans les yeux, j'y plonge profond\u00e9ment, en essayant d'attirer toute son attention et de la distraire de sa t\u00e2che. Je fais des blagues, je la fais sourire.<\/p>\n<p id=\"c8b3\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Et j'ai l'impression que \u00e7a marche. J'ai l'impression que plus je lui parle, plus l'id\u00e9e de trouver de la drogue ou un objet suspect dans mon sac s'\u00e9loigne de son esprit. Mais cette garce est tr\u00e8s professionnelle. Trop professionnelle. Elle continue de regarder et se rapproche.<\/p>\n<p id=\"2e25\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Elle s'est maintenant empar\u00e9e du kit de voyage d'Air France et l'\u00e9tudie. Mon c\u0153ur s'arr\u00eate de battre lorsqu'elle prend le petit sac en plastique transparent (<em class=\"ve\">avec les bouchons d'oreille et les pilules \u00e0 l'int\u00e9rieur<\/em>) de la trousse de voyage. \u00c7a y est, je suis foutu. Qu'est-ce que je vais bien pouvoir inventer pour qu'elle me laisse partir ? Mon cerveau fonctionne \u00e0 plein r\u00e9gime et les id\u00e9es fusent.<\/p>\n<p id=\"02e8\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Mais tout s'arr\u00eate quand elle prend la pochette en plastique juste entre nos paires d'yeux respectives. Je vis ce moment au ralenti et j'ai l'impression qu'il n'y a qu'elle, les bouchons d'oreille vert fluo, l'ecstasy rose et moi. Tout autour, c'est un immense vide noir, il n'y a plus de bruit, le temps s'est arr\u00eat\u00e9. Je ne vois que ces petits morceaux de mousse vert fluo et ces petites pilules roses, qui semblent encore plus visibles dans cette obscurit\u00e9 totale. J'ai perdu mes capacit\u00e9s c\u00e9r\u00e9brales, je ne pense plus. Je suis juste tr\u00e8s inqui\u00e8te. Pauvre m\u00e8re.<\/p>\n<p id=\"f482\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">La pochette en plastique dispara\u00eet progressivement de ma vue, au fur et \u00e0 mesure que la polici\u00e8re la pose sur la table. La lumi\u00e8re revient, le bruit aussi, l'environnement ext\u00e9rieur reprend le dessus. Les choses reviennent \u00e0 la normale. Sauf une chose. Une chose tr\u00e8s importante. La pochette est sur la table et la polici\u00e8re continue de regarder dans mon sac. Qu'est-ce que c'est que \u00e7a ? Cherche-t-elle autre chose ? Pourquoi ne dit-elle rien ? Parlez plus fort, bon sang ! Dis quelque chose, putain !<\/p>\n<p id=\"6e7f\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Mais elle ne le fait pas. Elle continue \u00e0 fouiller mon sac. Je me concentre maintenant sur la pochette en plastique laiss\u00e9e sur la table et je ne parle plus. Je commence \u00e0 penser qu'elle n'a peut-\u00eatre vu que du feu. Mais les pilules sont l\u00e0, bien visibles pour quiconque s'int\u00e9resse au contenu de mon sac sur la table. Et beaucoup de gens devraient s'y int\u00e9resser. J'ai affront\u00e9 la polici\u00e8re seule, mais beaucoup de ses coll\u00e8gues se tiennent ici, derri\u00e8re elle et autour de la table.<\/p>\n<p id=\"e6aa\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">Les secondes qui suivent semblent une \u00e9ternit\u00e9. Jusqu'\u00e0 ce qu'elle dise : \"D'accord, \u00e7a me va. Je vais te laisser ranger tes affaires si \u00e7a ne te d\u00e9range pas\".<br \/>\"Cela ne me d\u00e9range pas\", r\u00e9ponds-je.<\/p>\n<p id=\"fccd\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">J'attrape imm\u00e9diatement la pochette en plastique et la jette dans mon sac. En rangeant mes affaires, je n'en reviens pas. Comment se fait-il que je m'en sorte si bien ? Quel miracle !<\/p>\n<p id=\"e33b\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">D\u00e8s que j'arrive sur mon si\u00e8ge, je ne pense qu'\u00e0 une chose. Me d\u00e9barrasser de ces foutues pilules ! Une chose est s\u00fbre : Shane avait raison, m\u00eame sans avoir go\u00fbt\u00e9 \u00e0 son produit, il m'a fait vivre de sacr\u00e9es \u00e9motions !<\/p>\n<p id=\"bbd6\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">J'attrape donc le sac en plastique qui se trouve au fond de mon sac et je me dirige vers les toilettes pour les jeter. Ce faisant, je remarque que toutes les pilules d'ecstasy s'\u00e9taient gliss\u00e9es d'un seul c\u00f4t\u00e9 du sac en plastique lorsque je les y avais mises. Et sur le c\u00f4t\u00e9 droit ! Comprenez-moi bien, toutes les pilules ont gliss\u00e9 d'un SEUL c\u00f4t\u00e9. Selon le c\u00f4t\u00e9 o\u00f9 l'on regardait le sac, on pouvait voir toutes les pilules coinc\u00e9es entre les bouchons d'oreille d'un c\u00f4t\u00e9, ou juste les bouchons d'oreille de l'autre ! Lorsque la polici\u00e8re a sorti le sac et l'a regard\u00e9, j'ai pu voir toutes les pilules, alors que de son c\u00f4t\u00e9, elle n'a pu voir que les bouchons d'oreille !<\/p>\n<p id=\"a1ce\" class=\"pw-post-body-paragraph uk ul qn kp b um un uo up uq ur us ut jz uu uv uw ke ux uy uz kj va vb vc vd er bj\" data-selectable-paragraph=\"\">PUTAIN DE B\u00c2TARD CHANCEUX !!!<\/p>\n<ul class=\"wpuf_customs\">\n    <div class=\"google-map\" style=\"margin: 10px 0; height: 250px; width: 450px;\" id=\"wpuf-map-locate_your_story1638\"><\/div>\n\n    <script type=\"text\/javascript\">\n        jQuery(function($){\n            var curpoint = new google.maps.LatLng(21.0415454, -86.8869694);\n\n            var gmap = new google.maps.Map( $('#wpuf-map-locate_your_story1638')[0], {\n                center: curpoint,\n                zoom: 12,\n                mapTypeId: window.google.maps.MapTypeId.ROADMAP\n            });\n\n            var marker = new window.google.maps.Marker({\n                position: curpoint,\n                map: gmap,\n                draggable: true\n            });\n\n        });\n    <\/script>\n                            <div>\n                            <a class=\"btn btn-brand btn-sm\" href=\"https:\/\/www.google.com\/maps\/dir\/?api=1&amp;destination=21.0415454,-86.8869694\" target=\"_blank\" rel=\"nofollow external\">Directions \u00bb<\/a>\n                        <\/div>\n                        <\/ul>","protected":false},"excerpt":{"rendered":"<p>This Sunday of November, I leave Cancun (Mexico) for San Jose (Costa Rica), where I am supposed to meet my mum who I have [&hellip;]<\/p>","protected":false},"author":13,"featured_media":1639,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"stories-hashtags":[81,78],"class_list":["post-1638","story","type-story","status-publish","format-standard","has-post-thumbnail","hentry","stories-hashtags-drugs","stories-hashtags-lucky"],"acf":[],"_links":{"self":[{"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/story\/1638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/comments?post=1638"}],"version-history":[{"count":0,"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/story\/1638\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/media\/1639"}],"wp:attachment":[{"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/media?parent=1638"}],"wp:term":[{"taxonomy":"stories-hashtags","embeddable":true,"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/stories-hashtags?post=1638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}