{"id":1508,"date":"2024-02-29T06:15:08","date_gmt":"2024-02-29T06:15:08","guid":{"rendered":"https:\/\/luckybastards.co\/\/?post_type=story&#038;p=1508"},"modified":"2025-09-14T21:21:18","modified_gmt":"2025-09-14T21:21:18","slug":"bord-de-route","status":"publish","type":"story","link":"https:\/\/luckybastards.co\/fr\/story\/bord-de-route\/","title":{"rendered":"Bord de route"},"content":{"rendered":"<p class=\"wpc--darklup-element\"><span class=\"wpc--darklup-element darklup--text\">Epuis\u00e9s, bourr\u00e9s et bredouilles, Jocelyn et moi sommes sur le chemin du scooter pour rentrer \u00e0 la maison apr\u00e8s une nouvelle nuit enti\u00e8re de f\u00eate. Il est 5 ou 6 heures du matin, nos pas sont lourds, nos mines fatigu\u00e9es, notre discernement alt\u00e9r\u00e9.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"wpc--darklup-element\"><span class=\"wpc--darklup-element darklup--text\">A quelques m\u00e8tres du scooter, nous passons devant cette fille assise \u00e0 l\u2019entr\u00e9e d\u2019un parking. Lorsque Jocelyn l\u2019invective sans r\u00e9el espoir mais comme pour \u00eatre s\u00fbr de n\u2019\u00eatre pass\u00e9 \u00e0 c\u00f4t\u00e9 d\u2019aucune opportunit\u00e9, elle nous explique qu\u2019elle a perdu sa copine au milieu de la soir\u00e9e et que cette derni\u00e8re a les clefs de la voiture, toujours gar\u00e9e \u00e0 son emplacement de d\u00e9part.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"wpc--darklup-element\"><span class=\"wpc--darklup-element darklup--text\">Jocelyn est vraiment quelqu\u2019un de bien. Il a le coeur sur la main et est toujours pr\u00eat \u00e0 aider son prochain. Surtout quand le prochain est une prochaine et qu\u2019elle incarne l\u2019espoir d\u2019une soir\u00e9e qui finit en beaut\u00e9. C\u2019est donc tout naturellement qu\u2019il lui propose que nous l\u2019accueillions chez nous pour la nuit et que nous la d\u00e9posions chez elle le lendemain \u00e0 la premi\u00e8re heure.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"wpc--darklup-element\"><span class=\"wpc--darklup-element darklup--text\">Elle est fran\u00e7aise comme nous et nous lui inspirons confiance.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"wpc--darklup-element\"><span class=\"wpc--darklup-element darklup--text\">Ne se doutant pas de la montagne de vice qu\u2019elle s\u2019appr\u00eate \u00e0 gravir, la pauvre fille accepte l\u2019invitation et se glisse entre Jocelyn et moi sur le scooter, comme un pr\u00e9ambule \u00e0 la suite des \u00e9v\u00e9nements. La pauvre fille ou la chanceuse, cela d\u00e9pend de quel c\u00f4t\u00e9 on se place. Il faut dire qu\u2019elle n\u2019est pas vraiment le genre de fille sur laquelle nous nous serions arr\u00eat\u00e9s en temps normal. Elle n\u2019est pourtant pas laide, elle a m\u00eame de tr\u00e8s jolis yeux, de plut\u00f4t belles formes et une poitrine g\u00e9n\u00e9reuse. Mais elle n\u2019est pas attirante pour un sou. La mani\u00e8re dont elle est habill\u00e9e, sa fa\u00e7on de parler, le fait que nous l\u2019ayons \u00ab\u00a0ramass\u00e9e\u00a0\u00bb dans la rue et surtout l\u2019odeur qui se d\u00e9gage de ses chaussures lorsqu\u2019elle les retires une fois arriv\u00e9s \u00e0 la maison ne constituent pas des points en sa faveur.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"wpc--darklup-element\"><span class=\"wpc--darklup-element darklup--text\">Tout \u00e7a n\u2019est pas pass\u00e9 inaper\u00e7u aupr\u00e8s de ce vicelard de Jocelyn qui nous souhaite bonne nuit et va se coucher dans la chambre o\u00f9 dort notre pote Dan, en me laissant gentiment partager le canap\u00e9-lit du salon avec notre invit\u00e9e de derni\u00e8re minute (qui me rejoint apr\u00e8s avoir tout de m\u00eame pris le soin de prendre une douche).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"wpc--darklup-element\"><span class=\"wpc--darklup-element darklup--text\">L\u2019enfoir\u00e9 quitte le navire \u00e0 la premi\u00e8re difficult\u00e9 et me laisse seul avec la fille qu\u2019il a lui m\u00eame ramen\u00e9e \u00e0 la maison. Nul besoin de se parler pourtant pour savoir lui comme moi que nous nous dirigions initialement vers un plan \u00e0 trois qui allait prendre forme sans aucun doute. Nous n\u2019en sommes pas \u00e0 notre coup d\u2019essai, nous savons comment ces histoires se d\u00e9roulent, nous connaissons leur \u00e9volution, leurs \u00e9ventuelles barri\u00e8res, les mani\u00e8res de les sauter et leur d\u00e9nouement. Nul besoin non plus de pr\u00e9ciser qu\u2019il s\u2019agissait d\u2019un \u00ab\u00a0travail\u00a0\u00bb d\u2019\u00e9quipe, pas d\u2019un one to one. L\u2019attrait physique d\u2019un coup d\u2019un soir n\u2019a que peu d\u2019importance lorsqu\u2019il est v\u00e9cu entre copains et qu\u2019il vient \u00e9crire une nouvelle page au livre de notre amiti\u00e9.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"wpc--darklup-element\"><span class=\"wpc--darklup-element darklup--text\">Il faut dire que Jocelyn vient de passer plusieurs jours de baise intense avec une am\u00e9ricaine rencontr\u00e9e quelques jours plus t\u00f4t \u00e0 Ath\u00e8nes, qu\u2019il sait que les plans \u00e0 plusieurs ne sont pas ma tasse de th\u00e9 et que ces vacances n\u2019ont pas \u00e9t\u00e9 glorieuses pour moi en termes d\u2019\u00e9panouissement sexuel. Il me dira le lendemain avoir voulu \u00eatre sympa avec moi et me laisser tranquille avec elle. Soit\u2026 Je pr\u00e9f\u00e8re ne pas m\u2019\u00e9tendre ici sur le personnage, il faudrait pour cela un livre entier.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"wpc--darklup-element\"><span class=\"wpc--darklup-element darklup--text\">\u00c9puis\u00e9, je me couche donc sans grandes ambitions pour notre nouvelle amie et m\u2019appr\u00eate \u00e0 m\u2019endormir paisiblement. Manifestement pas tr\u00e8s int\u00e9ress\u00e9e par cette version de l\u2019histoire, c\u2019est avec une pointe de provocation qu\u2019elle me fait part de son soulagement de constater que nous n\u2019allions pas \u00ab\u00a0lui faire de mal\u00a0\u00bb. J\u2019ai beau \u00eatre fatigu\u00e9, je ne peux raisonnablement pas laiss\u00e9 passer une telle r\u00e9flexion. Et puis j\u2019ai ma part de sensibilit\u00e9 moi aussi. La pauvre fille a d\u00fb joyeusement s\u2019imaginer que nous nous occuperions tous les deux d\u2019elle pendant des heures, il serait ind\u00e9cent et tr\u00e8s impoli de la laisser ainsi. Je m\u2019ex\u00e9cute donc. Pendant 7 minutes\u2026 Certainement loin des espoirs qu\u2019elle pla\u00e7ait en nous mais suffisant pour que je consid\u00e8re avoir fait ma part du travail, lui tourne le dos et m\u2019endorme sereinement.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"wpc--darklup-element\"><span class=\"wpc--darklup-element darklup--text\">En bons gentlemen, nous l\u2019avons d\u00e9pos\u00e9e le lendemain comme promis, sans \u00e9change de contact ou perspective de nous revoir. Elle nous remercia pour les services rendus avant de dispara\u00eetre \u00e0 jamais dans la chaleur de Mikonos.<\/span><\/p>\n<ul class=\"wpuf_customs\">\n    <div class=\"google-map\" style=\"margin: 10px 0; height: 250px; width: 450px;\" id=\"wpuf-map-locate_your_story1508\"><\/div>\n\n    <script type=\"text\/javascript\">\n        jQuery(function($){\n            var curpoint = new google.maps.LatLng(37.4291074, 25.3177983);\n\n            var gmap = new google.maps.Map( $('#wpuf-map-locate_your_story1508')[0], {\n                center: curpoint,\n                zoom: 12,\n                mapTypeId: window.google.maps.MapTypeId.ROADMAP\n            });\n\n            var marker = new window.google.maps.Marker({\n                position: curpoint,\n                map: gmap,\n                draggable: true\n            });\n\n        });\n    <\/script>\n                            <div>\n                            <a class=\"btn btn-brand btn-sm\" href=\"https:\/\/www.google.com\/maps\/dir\/?api=1&amp;destination=37.4291074,25.3177983\" target=\"_blank\" rel=\"nofollow external\">Directions \u00bb<\/a>\n                        <\/div>\n                        <\/ul>","protected":false},"excerpt":{"rendered":"<p>Epuis\u00e9s, bourr\u00e9s et bredouilles, Jocelyn et moi sommes sur le chemin du scooter pour rentrer \u00e0 la maison apr\u00e8s une nouvelle nuit enti\u00e8re de [&hellip;]<\/p>","protected":false},"author":30,"featured_media":1509,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"stories-hashtags":[82,89,86],"class_list":["post-1508","story","type-story","status-publish","format-standard","has-post-thumbnail","hentry","stories-hashtags-funny","stories-hashtags-hot","stories-hashtags-unexpected"],"acf":[],"_links":{"self":[{"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/story\/1508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/comments?post=1508"}],"version-history":[{"count":0,"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/story\/1508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/media\/1509"}],"wp:attachment":[{"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/media?parent=1508"}],"wp:term":[{"taxonomy":"stories-hashtags","embeddable":true,"href":"https:\/\/luckybastards.co\/fr\/wp-json\/wp\/v2\/stories-hashtags?post=1508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}